{"id":19992,"date":"2023-07-13T11:26:34","date_gmt":"2023-07-13T09:26:34","guid":{"rendered":"https:\/\/www.sharesub.com\/cms\/como-cancelar-xbox-game-pass\/"},"modified":"2026-04-22T13:28:56","modified_gmt":"2026-04-22T11:28:56","slug":"como-cancelar-xbox-game-pass","status":"publish","type":"post","link":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/","title":{"rendered":"C\u00f3mo cancelar Xbox Game Pass"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Xbox Game Pass se ha convertido en un servicio esencial para todos los jugadores. Adem\u00e1s de permitirte jugar con tus amigos, tambi\u00e9n te da <strong>acceso a m\u00e1s de 300 juegos gratuitos<\/strong>, y francamente, no se puede discutir con eso dada la calidad de los t\u00edtulos que se ofrecen. Sin embargo, es posible que desee cancelar su suscripci\u00f3n por varias razones, ya sea para reducir sus gastos mensuales o simplemente porque ya no utiliza el servicio.  <\/p>\n\n<h2 class=\"wp-block-heading\">Una soluci\u00f3n rentable: los abonos compartidos  <\/h2>\n\n<p class=\"wp-block-paragraph\">Si el principal motivo para cancelar la suscripci\u00f3n es el precio, hay formas de reducir los gastos.  <a href=\"https:\/\/www.sharesub.com\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Sharesub.com <\/a>es un sitio especializado en suscripciones compartidas que te permite a ti, jugador, seguir disfrutando de tus juegos favoritos mientras ahorras dinero. Lo \u00fanico que tienes que hacer es compartir las plazas disponibles en tu abono Game Pass y dividir por 2 el precio de tu abono.<\/p>\n\n<p class=\"wp-block-paragraph\">Si tienes una suscripci\u00f3n a Xbox Game Pass \u27a1\ufe0f <a href=\"https:\/\/www.sharesub.com\/es\" target=\"_blank\" rel=\"noreferrer noopener\">Compartir mi suscripci\u00f3n <\/a> <\/p>\n\n<p class=\"wp-block-paragraph\">Si a\u00fan no est\u00e1 abonado \u27a1\ufe0f <a href=\"https:\/\/www.sharesub.com\/es\/brand\/xbox\" target=\"_blank\" rel=\"noreferrer noopener\">Abonarse<\/a><\/p>\n\n<h2 class=\"wp-block-heading\">C\u00f3mo cancelar la suscripci\u00f3n a Xbox Game Pass desde la consola  <\/h2>\n\n<p class=\"wp-block-paragraph\">Si decides cancelar tu suscripci\u00f3n a Xbox Game Pass, sigue estos pasos:<\/p>\n\n<p class=\"wp-block-paragraph\">1. Pulsa el bot\u00f3n <strong>\u00abXbox\u00bb<\/strong> de tu mando para mostrar la pantalla de inicio.  <\/p>\n\n<p class=\"wp-block-paragraph\">2. Vaya a <strong>\u00abPerfil y sistema\u00bb<\/strong> y luego a <strong>\u00abAjustes<\/strong>\u00ab.<\/p>\n\n<p class=\"wp-block-paragraph\">3. A continuaci\u00f3n, en <strong>\u00abCuenta\u00bb<\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\">4. En el men\u00fa que aparece, vaya a<strong> \u00abSuscripci\u00f3n\u00bb <\/strong>.  <\/p>\n\n<p class=\"wp-block-paragraph\">5. Despl\u00e1zate hacia abajo para encontrar tu suscripci\u00f3n a <strong>\u00abXbox Game Pass <\/strong>\u00ab.  <\/p>\n\n<p class=\"wp-block-paragraph\">6. Por \u00faltimo, seleccione <strong>\u00abCancelar suscripci\u00f3n\u00bb<\/strong>.<\/p>\n\n<p class=\"wp-block-paragraph\">7. Confirme  <\/p>\n\n<h2 class=\"wp-block-heading\">C\u00f3mo cancelar la suscripci\u00f3n a Xbox Game Pass mediante un navegador  <\/h2>\n\n<p class=\"wp-block-paragraph\">Si decides cancelar tu suscripci\u00f3n desde tu navegador, estos son los pasos a seguir;  <\/p>\n\n<p class=\"wp-block-paragraph\">1. Inicie sesi\u00f3n en<a href=\"https:\/\/account.microsoft.com\/account\/Account?ru=https%3A%2F%2Faccount.microsoft.com%2F&amp;destrt=home.landing\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abaccount.microsoft.com<\/a>\u00ab.<\/p>\n\n<p class=\"wp-block-paragraph\">2. Vaya a \u00abSuscripciones\u00bb.  <\/p>\n\n<p class=\"wp-block-paragraph\">3. Seleccione \u00abMostrar todas las suscripciones\u00bb y luego \u00abGestionar\u00bb.  <\/p>\n\n<p class=\"wp-block-paragraph\">4. Seleccione \u00abCancelar suscripci\u00f3n\u00bb.  <\/p>\n\n<p class=\"has-vivid-green-cyan-background-color has-background wp-block-paragraph\">Es importante tener en cuenta que <strong>cancelar la suscripci\u00f3n<\/strong> supondr\u00e1 la <strong>p\u00e9rdida de acceso a todos los juegos disponibles<\/strong> a trav\u00e9s de Xbox Game Pass. Ya no podr\u00e1s jugar hasta que hayas reactivado tu suscripci\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\">\u00bfPerder\u00e9 el acceso a los juegos de Game Pass si cancelo mi suscripci\u00f3n?<\/h2>\n\n<p class=\"wp-block-paragraph\">S\u00ed, una vez que canceles tu suscripci\u00f3n, perder\u00e1s el acceso a todos los juegos incluidos en Xbox Game Pass. Podr\u00e1s volver a jugar cuando se restablezca tu suscripci\u00f3n.<\/p>\n\n<h2 class=\"wp-block-heading\">Paga menos por Xbox Game Pass  <\/h2>\n\n<p class=\"wp-block-paragraph\">Compartir la suscripci\u00f3n es la forma m\u00e1s f\u00e1cil de ahorrar dinero en tu Game Pass.<\/p>\n\n<h2 class=\"wp-block-heading\">\u00bfPuedo reactivar mi suscripci\u00f3n a Xbox Game Pass despu\u00e9s de cancelarla?<\/h2>\n\n<p class=\"wp-block-paragraph\">S\u00ed, puedes reactivar tu suscripci\u00f3n en cualquier momento iniciando sesi\u00f3n en tu cuenta Xbox o Microsoft y volviendo a suscribirte a Xbox Game Pass en la plataforma Sharesub.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Xbox Game Pass se ha convertido en un servicio esencial para todos los jugadores. Adem\u00e1s de permitirte jugar con tus amigos, tambi\u00e9n te da acceso&#8230;<\/p>\n","protected":false},"author":3,"featured_media":19968,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_press_lang":"","_press_original_id":"","_press_pair_id":"","_press_translated_at":"","footnotes":""},"categories":[142],"tags":[],"class_list":["post-19992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-videojuegos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00f3mo cancelar Xbox Game Pass - Sharesub<\/title>\n<meta name=\"description\" content=\"Si el principal motivo para cancelar la suscripci\u00f3n es el precio, hay formas de reducir los gastos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo cancelar Xbox Game Pass - Sharesub\" \/>\n<meta property=\"og:description\" content=\"Si el principal motivo para cancelar la suscripci\u00f3n es el precio, hay formas de reducir los gastos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/\" \/>\n<meta property=\"og:site_name\" content=\"Sharesub\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-13T09:26:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-22T11:28:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sharesub.com\/cms\/wp-content\/uploads\/2023\/07\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"719\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Benjamin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benjamin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/\"},\"author\":{\"name\":\"Benjamin\",\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/#\\\/schema\\\/person\\\/79a38917f5123b295226d2c7f6ea1b06\"},\"headline\":\"C\u00f3mo cancelar Xbox Game Pass\",\"datePublished\":\"2023-07-13T09:26:34+00:00\",\"dateModified\":\"2026-04-22T11:28:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/\"},\"wordCount\":464,\"image\":{\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg\",\"articleSection\":[\"Videojuegos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/\",\"url\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/\",\"name\":\"C\u00f3mo cancelar Xbox Game Pass - Sharesub\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg\",\"datePublished\":\"2023-07-13T09:26:34+00:00\",\"dateModified\":\"2026-04-22T11:28:56+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/#\\\/schema\\\/person\\\/79a38917f5123b295226d2c7f6ea1b06\"},\"description\":\"Si el principal motivo para cancelar la suscripci\u00f3n es el precio, hay formas de reducir los gastos.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/como-cancelar-xbox-game-pass\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg\",\"width\":719,\"height\":480},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/\",\"name\":\"Sharesub\",\"description\":\"Partage d&#039;abonnement\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sharesub.com\\\/cms\\\/es\\\/#\\\/schema\\\/person\\\/79a38917f5123b295226d2c7f6ea1b06\",\"name\":\"Benjamin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo cancelar Xbox Game Pass - Sharesub","description":"Si el principal motivo para cancelar la suscripci\u00f3n es el precio, hay formas de reducir los gastos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo cancelar Xbox Game Pass - Sharesub","og_description":"Si el principal motivo para cancelar la suscripci\u00f3n es el precio, hay formas de reducir los gastos.","og_url":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/","og_site_name":"Sharesub","article_published_time":"2023-07-13T09:26:34+00:00","article_modified_time":"2026-04-22T11:28:56+00:00","og_image":[{"width":719,"height":480,"url":"https:\/\/www.sharesub.com\/cms\/wp-content\/uploads\/2023\/07\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg","type":"image\/jpeg"}],"author":"Benjamin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Benjamin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/#article","isPartOf":{"@id":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/"},"author":{"name":"Benjamin","@id":"https:\/\/www.sharesub.com\/cms\/es\/#\/schema\/person\/79a38917f5123b295226d2c7f6ea1b06"},"headline":"C\u00f3mo cancelar Xbox Game Pass","datePublished":"2023-07-13T09:26:34+00:00","dateModified":"2026-04-22T11:28:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/"},"wordCount":464,"image":{"@id":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sharesub.com\/cms\/wp-content\/uploads\/2023\/07\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg","articleSection":["Videojuegos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/","url":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/","name":"C\u00f3mo cancelar Xbox Game Pass - Sharesub","isPartOf":{"@id":"https:\/\/www.sharesub.com\/cms\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/#primaryimage"},"image":{"@id":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sharesub.com\/cms\/wp-content\/uploads\/2023\/07\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg","datePublished":"2023-07-13T09:26:34+00:00","dateModified":"2026-04-22T11:28:56+00:00","author":{"@id":"https:\/\/www.sharesub.com\/cms\/es\/#\/schema\/person\/79a38917f5123b295226d2c7f6ea1b06"},"description":"Si el principal motivo para cancelar la suscripci\u00f3n es el precio, hay formas de reducir los gastos.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sharesub.com\/cms\/es\/como-cancelar-xbox-game-pass\/#primaryimage","url":"https:\/\/www.sharesub.com\/cms\/wp-content\/uploads\/2023\/07\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg","contentUrl":"https:\/\/www.sharesub.com\/cms\/wp-content\/uploads\/2023\/07\/480_F_141791836_z90PCBth1q1cgy35V3sM7QF8g8PuGMk5.jpg","width":719,"height":480},{"@type":"WebSite","@id":"https:\/\/www.sharesub.com\/cms\/es\/#website","url":"https:\/\/www.sharesub.com\/cms\/es\/","name":"Sharesub","description":"Partage d&#039;abonnement","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sharesub.com\/cms\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.sharesub.com\/cms\/es\/#\/schema\/person\/79a38917f5123b295226d2c7f6ea1b06","name":"Benjamin"}]}},"_links":{"self":[{"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/posts\/19992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/comments?post=19992"}],"version-history":[{"count":7,"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/posts\/19992\/revisions"}],"predecessor-version":[{"id":59104,"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/posts\/19992\/revisions\/59104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/media\/19968"}],"wp:attachment":[{"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/media?parent=19992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/categories?post=19992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sharesub.com\/cms\/es\/wp-json\/wp\/v2\/tags?post=19992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}